{"id":9,"date":"2025-04-14T15:06:40","date_gmt":"2025-04-14T15:06:40","guid":{"rendered":"https:\/\/www.westchestergentledentistry.com\/blog\/?p=9"},"modified":"2026-05-21T20:27:48","modified_gmt":"2026-05-21T20:27:48","slug":"new-patient-special-offer-at-westchester-gentle-dentistry","status":"publish","type":"post","link":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/","title":{"rendered":"New Patient Special Offer at Westchester Gentle Dentistry"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">For patients visiting our office for the first time, we have a <a href=\"https:\/\/www.westchestergentledentistry.com\/special-offers.html\">special offer<\/a> that includes an exam, X-rays, a consultation with the doctor and a written treatment plan.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\">Highly Skilled, Personalized Dentistry<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dr. Feryal Alidadi has been providing comprehensive family and cosmetic dental services to residents of Port Chester, White Plains and Westchester County for over 20 years. <a href=\"https:\/\/www.westchestergentledentistry.com\/meet-dr-alidadi.html\">Dr. Alidadi<\/a> emphasizes patient comfort as well as staying up-to-date with the latest developments in dentistry to give you the best treatment possible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.westchestergentledentistry.com\/about-us.html#making-you-feel-comfortable\"><strong>Gentle and Friendly Care<\/strong><\/a>Dr. Alidadi is known for her gentle touch, friendly smile and kind heart. She and our professional staff will put you ease, listen to your concerns and keep your comfortable throughout your visit.<br><br>Dr. Alidadi will take the time to you discuss your dental concerns and goals. She will answer all your questions. After doing a thorough exam, she will discuss her diagnosis and recommended treatment options with you.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">New Patient Special<br>$99 Exam, X-Rays and Consultation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Take advantage of this special offer that includes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Comprehensive oral exam<\/li>\n\n\n\n<li>Digital intraoral scanner (iTero)<\/li>\n\n\n\n<li>Digital full-mouth X-rays<\/li>\n\n\n\n<li>Periodontal (gum) exam<\/li>\n\n\n\n<li>Examine your TMJ (jaw joint)<\/li>\n\n\n\n<li>Check for teeth&nbsp;<a href=\"https:\/\/www.westchestergentledentistry.com\/emergency-dentistry.html\">grinding<\/a><\/li>\n\n\n\n<li>Get all questions answered<\/li>\n\n\n\n<li>Customized treatment plan<\/li>\n\n\n\n<li>Discuss treatment options<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A $350 value! Valid for new patients only.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">To make an appointment, call 914\u2011289\u20110672 or\u00a0<a href=\"https:\/\/www.westchestergentledentistry.com\/contact.html#form\">click here<\/a>\u00a0to request an appointment online.<\/p>\n","protected":false},"excerpt":{"rendered":"For patients visiting our office for the first time, we have a special offer that includes an exam, X-rays, a consultation with the doctor and a written treatment plan. <a class=\"read-more\" href=\"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/\">(Read More)<\/a>","protected":false},"author":2,"featured_media":10,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New Patient Special Offer Port Chester, NY | Westchester Gentle Dentistry<\/title>\n<meta name=\"description\" content=\"Save money on your first dental visit at Westchester Gentle Dentistry with this special offer for new patients.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Patient Special Offer Port Chester, NY | Westchester Gentle Dentistry\" \/>\n<meta property=\"og:description\" content=\"Save money on your first dental visit at Westchester Gentle Dentistry with this special offer for new patients.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/\" \/>\n<meta property=\"og:site_name\" content=\"Westchester Gentle Dentistry Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Westchester-Gentle-Dentistry\/100054432761863\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-14T15:06:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-21T20:27:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.westchestergentledentistry.com\/blog\/wp-content\/uploads\/2025\/04\/crowns-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Westchester Gentle Dentistry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Westchester Gentle Dentistry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/\"},\"author\":{\"name\":\"Westchester Gentle Dentistry\",\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/#\\\/schema\\\/person\\\/f9ffed2ea85c64108b81ae681e5450fd\"},\"headline\":\"New Patient Special Offer at Westchester Gentle Dentistry\",\"datePublished\":\"2025-04-14T15:06:40+00:00\",\"dateModified\":\"2026-05-21T20:27:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/\"},\"wordCount\":230,\"publisher\":{\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/crowns-1.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/\",\"url\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/\",\"name\":\"New Patient Special Offer Port Chester, NY | Westchester Gentle Dentistry\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/crowns-1.jpg\",\"datePublished\":\"2025-04-14T15:06:40+00:00\",\"dateModified\":\"2026-05-21T20:27:48+00:00\",\"description\":\"Save money on your first dental visit at Westchester Gentle Dentistry with this special offer for new patients.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/crowns-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/crowns-1.jpg\",\"width\":300,\"height\":300,\"caption\":\"A dentist in a white coat shows a dental model to a smiling woman in a yellow shirt, seated in a dental office\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/2025\\\/04\\\/14\\\/new-patient-special-offer-at-westchester-gentle-dentistry\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New Patient Special Offer at Westchester Gentle Dentistry\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/\",\"name\":\"Westchester Gentle Dentistry Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/#organization\"},\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/#organization\",\"name\":\"Westchester Gentle Dentistry Blog\",\"url\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/site-logo-v1.png\",\"contentUrl\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/site-logo-v1.png\",\"width\":596,\"height\":235,\"caption\":\"Westchester Gentle Dentistry Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Westchester-Gentle-Dentistry\\\/100054432761863\\\/\",\"https:\\\/\\\/www.instagram.com\\\/westchestergdentistry\\\/?hl=en\",\"https:\\\/\\\/www.youtube.com\\\/@WestchesterGentleDentistry?app=desktop\",\"https:\\\/\\\/maps.app.goo.gl\\\/bSTkmc8icHbMzWHy9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.westchestergentledentistry.com\\\/blog\\\/#\\\/schema\\\/person\\\/f9ffed2ea85c64108b81ae681e5450fd\",\"name\":\"Westchester Gentle Dentistry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba0365835ccfc533990fd2b4ea4090adc9dc5d2bcdb2d87e77da3c2b0323e802?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba0365835ccfc533990fd2b4ea4090adc9dc5d2bcdb2d87e77da3c2b0323e802?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba0365835ccfc533990fd2b4ea4090adc9dc5d2bcdb2d87e77da3c2b0323e802?s=96&d=mm&r=g\",\"caption\":\"Westchester Gentle Dentistry\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Patient Special Offer Port Chester, NY | Westchester Gentle Dentistry","description":"Save money on your first dental visit at Westchester Gentle Dentistry with this special offer for new patients.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/","og_locale":"en_US","og_type":"article","og_title":"New Patient Special Offer Port Chester, NY | Westchester Gentle Dentistry","og_description":"Save money on your first dental visit at Westchester Gentle Dentistry with this special offer for new patients.","og_url":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/","og_site_name":"Westchester Gentle Dentistry Blog","article_publisher":"https:\/\/www.facebook.com\/people\/Westchester-Gentle-Dentistry\/100054432761863\/","article_published_time":"2025-04-14T15:06:40+00:00","article_modified_time":"2026-05-21T20:27:48+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-content\/uploads\/2025\/04\/crowns-1.jpg","type":"image\/jpeg"}],"author":"Westchester Gentle Dentistry","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Westchester Gentle Dentistry","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/#article","isPartOf":{"@id":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/"},"author":{"name":"Westchester Gentle Dentistry","@id":"https:\/\/www.westchestergentledentistry.com\/blog\/#\/schema\/person\/f9ffed2ea85c64108b81ae681e5450fd"},"headline":"New Patient Special Offer at Westchester Gentle Dentistry","datePublished":"2025-04-14T15:06:40+00:00","dateModified":"2026-05-21T20:27:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/"},"wordCount":230,"publisher":{"@id":"https:\/\/www.westchestergentledentistry.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/#primaryimage"},"thumbnailUrl":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-content\/uploads\/2025\/04\/crowns-1.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/","url":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/","name":"New Patient Special Offer Port Chester, NY | Westchester Gentle Dentistry","isPartOf":{"@id":"https:\/\/www.westchestergentledentistry.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/#primaryimage"},"image":{"@id":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/#primaryimage"},"thumbnailUrl":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-content\/uploads\/2025\/04\/crowns-1.jpg","datePublished":"2025-04-14T15:06:40+00:00","dateModified":"2026-05-21T20:27:48+00:00","description":"Save money on your first dental visit at Westchester Gentle Dentistry with this special offer for new patients.","breadcrumb":{"@id":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/#primaryimage","url":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-content\/uploads\/2025\/04\/crowns-1.jpg","contentUrl":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-content\/uploads\/2025\/04\/crowns-1.jpg","width":300,"height":300,"caption":"A dentist in a white coat shows a dental model to a smiling woman in a yellow shirt, seated in a dental office"},{"@type":"BreadcrumbList","@id":"https:\/\/www.westchestergentledentistry.com\/blog\/2025\/04\/14\/new-patient-special-offer-at-westchester-gentle-dentistry\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.westchestergentledentistry.com\/blog\/"},{"@type":"ListItem","position":2,"name":"New Patient Special Offer at Westchester Gentle Dentistry"}]},{"@type":"WebSite","@id":"https:\/\/www.westchestergentledentistry.com\/blog\/#website","url":"https:\/\/www.westchestergentledentistry.com\/blog\/","name":"Westchester Gentle Dentistry Blog","description":"","publisher":{"@id":"https:\/\/www.westchestergentledentistry.com\/blog\/#organization"},"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.westchestergentledentistry.com\/blog\/#organization","name":"Westchester Gentle Dentistry Blog","url":"https:\/\/www.westchestergentledentistry.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.westchestergentledentistry.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-content\/uploads\/2025\/08\/site-logo-v1.png","contentUrl":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-content\/uploads\/2025\/08\/site-logo-v1.png","width":596,"height":235,"caption":"Westchester Gentle Dentistry Blog"},"image":{"@id":"https:\/\/www.westchestergentledentistry.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Westchester-Gentle-Dentistry\/100054432761863\/","https:\/\/www.instagram.com\/westchestergdentistry\/?hl=en","https:\/\/www.youtube.com\/@WestchesterGentleDentistry?app=desktop","https:\/\/maps.app.goo.gl\/bSTkmc8icHbMzWHy9"]},{"@type":"Person","@id":"https:\/\/www.westchestergentledentistry.com\/blog\/#\/schema\/person\/f9ffed2ea85c64108b81ae681e5450fd","name":"Westchester Gentle Dentistry","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ba0365835ccfc533990fd2b4ea4090adc9dc5d2bcdb2d87e77da3c2b0323e802?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba0365835ccfc533990fd2b4ea4090adc9dc5d2bcdb2d87e77da3c2b0323e802?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba0365835ccfc533990fd2b4ea4090adc9dc5d2bcdb2d87e77da3c2b0323e802?s=96&d=mm&r=g","caption":"Westchester Gentle Dentistry"}}]}},"_links":{"self":[{"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/posts\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":2,"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/posts\/9\/revisions"}],"predecessor-version":[{"id":109,"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/posts\/9\/revisions\/109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/media\/10"}],"wp:attachment":[{"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/media?parent=9"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/categories?post=9"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.westchestergentledentistry.com\/blog\/wp-json\/wp\/v2\/tags?post=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}